{"id":10649,"date":"2022-09-25T09:17:23","date_gmt":"2022-09-25T07:17:23","guid":{"rendered":"https:\/\/diamantaire-paris.com\/?page_id=10649"},"modified":"2026-06-09T18:44:28","modified_gmt":"2026-06-09T16:44:28","slug":"cosmos","status":"publish","type":"page","link":"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/cosmos\/","title":{"rendered":"Selling the Van Cleef &amp; Arpels Cosmos collection"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10649\" class=\"elementor elementor-10649\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f53722c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f53722c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d943f16\" data-id=\"5d943f16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77cc0e62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77cc0e62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-50abb071\" data-id=\"50abb071\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54dfd910 elementor-widget elementor-widget-image\" data-id=\"54dfd910\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/van-cleef-and-arpels\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef-683x1024.png\" class=\"attachment-large size-large wp-image-19933\" alt=\"Bague Van Cleef \u00e0 expertiser\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef-683x1024.png 683w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef-200x300.png 200w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef-768x1152.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef-8x12.png 8w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2025\/08\/Bague-Van-Cleef.png 1024w\" sizes=\"(max-width: 683px) 100vw, 683px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ea3d8d9\" data-id=\"3ea3d8d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5802fc33 elementor-widget elementor-widget-heading\" data-id=\"5802fc33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Expertisez vos bijoux Van Cleef &amp; Arpels <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61ce8360 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61ce8360\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-446d8a1e\" data-id=\"446d8a1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71d98d4d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"71d98d4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0148878144\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">01 48 87 81 44\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c729e2e\" data-id=\"5c729e2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79087e15 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"79087e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=33148872337&#038;text&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vendre<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b51e06 elementor-widget elementor-widget-google_maps\" data-id=\"5b51e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=diamantaire%20paris%20OG&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"diamantaire paris OG\"\n\t\t\t\t\taria-label=\"diamantaire paris OG\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9045751 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9045751\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa9daff\" data-id=\"fa9daff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20b6789 elementor-widget elementor-widget-shortcode\" data-id=\"20b6789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Diamantaires Paris<\/span><\/p><\/nav>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67bac86 elementor-widget elementor-widget-image\" data-id=\"67bac86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"419\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-1024x536.jpg\" class=\"attachment-large size-large wp-image-10653\" alt=\"Vendre bijou collection Cosmos\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-1024x536.jpg 1024w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-300x157.jpg 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-768x402.jpg 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-884412f elementor-widget elementor-widget-text-editor\" data-id=\"884412f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><a href=\"https:\/\/diamantaire-paris.com\/acheter-diamant\/parure-van-cleef-arpels-vintage\/\">La Maison Van Cleef &amp; Arpels<\/a>, c\u2019est un m\u00e9lange d\u2019\u00e9l\u00e9gance et de savoir-faire. Les bijoux Van Cleef &amp; Arpels sont uniques gr\u00e2ce \u00e0 des techniques brevet\u00e9es, et \u00e0 des motifs inspir\u00e9s de la Nature stylis\u00e9s par les plus grands designers. Van Cleef &amp; Arpels est aujourd\u2019hui l\u2019un des Joailliers de luxe qui repr\u00e9sentent le plus l\u2019excellence \u00e0 la fran\u00e7aise. Vous poss\u00e9dez un bijou de la collection Cosmos de Van Cleef &amp; Arpels ? D\u00e9couvrez <a href=\"https:\/\/diamantaire-paris.com\/van-cleef-and-arpels\/\">comment vendre un bijou Van Cleef &amp; Arpels au meilleur prix.<\/a><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5f45fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5f45fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21ee575\" data-id=\"21ee575\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f018763 elementor-widget elementor-widget-heading\" data-id=\"f018763\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u2019histoire de la Maison Van Cleef &amp; Arpels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9981235 elementor-widget elementor-widget-text-editor\" data-id=\"9981235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Maison Van Cleef &amp; Arpels a \u00e9t\u00e9 fond\u00e9e par Estelle Arpels (fille d\u2019un n\u00e9gociant en pierres pr\u00e9cieuses) et Alfred Van Cleef (fils d\u2019un diamantaire) \u00e0 la fin des ann\u00e9es 1890. D\u00e8s 1906, la Maison de Joaillerie s\u2019installait Place Vend\u00f4me, au num\u00e9ro 22. Depuis, elle n\u2019a cess\u00e9 d\u2019impressionner par son savoir-faire, avec des techniques brevet\u00e9es comme le Serti Myst\u00e9rieux, et des collections \u00e0 la fois luxueuses et \u00e9pur\u00e9es.\u00a0La Maison Van Cleef &amp; Arpels a notamment produit la parure de fian\u00e7ailles de la Princesse Grace de Monaco ou encore le c\u00e9l\u00e8bre bracelet jarreti\u00e8re de Marl\u00e8ne Dietrich dans le film d\u2019Hitchcock <em>Le Grand Alibi<\/em>. En 1937, la Maison Van Cleef &amp; Arpels s\u2019est montr\u00e9e pionni\u00e8re en \u00e9tant la premi\u00e8re Maison\u00a0 de Haute Joaillerie fran\u00e7aise \u00e0 s\u2019installer au Japon. La collection Cosmos a \u00e9t\u00e9 cr\u00e9\u00e9e en 2014 et s\u2019inspire, comme de nombreuses collections de Van Cleef &amp; Arpels (Fleurette, Lotus\u2026) d\u2019une fleur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7963ac9 elementor-widget elementor-widget-heading\" data-id=\"7963ac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La collection Cosmos Van Cleef &amp; Arpels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81b7cfb elementor-widget elementor-widget-text-editor\" data-id=\"81b7cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La collection Cosmos reprend une fleur signature de Van Cleef &amp; Arpels qui avait \u00e9t\u00e9 cr\u00e9\u00e9e dans les ann\u00e9es 50. Cette fleur est compos\u00e9e de 4 p\u00e9tales en forme de c\u0153ur, dans un motif inspir\u00e9 du tr\u00e8fle \u00e0 4 feuilles. Les mat\u00e9riaux \u00e0 l\u2019honneur \u00e0 travers cette collection de magnifiques bijoux minimalistes sont le nacre et l\u2019onyx. On trouve ainsi deux combinaisons\u00a0: une ligne de bijoux avec de l\u2019or rose, du nacre et des diamants, et une autre avec de l\u2019or blanc, de l\u2019onyx et des diamants. Les bijoux de la collection Cosmos, \u00e0 savoir des bagues, boucles d\u2019oreilles et pendentifs, valent entre 9\u00a0400 \u20ac et 17\u00a0900 \u20ac.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9eba87 elementor-widget elementor-widget-heading\" data-id=\"d9eba87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment vendre un bijou collection Cosmos Van Cleef &amp; Arpels ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-140e38d elementor-widget elementor-widget-text-editor\" data-id=\"140e38d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous souhaitez vendre un bijou de la collection Cosmos de Van Cleef &amp; Arpels\u00a0? Cette collection de 2014 est tr\u00e8s pris\u00e9e et vous trouverez facilement des acheteurs. Pour simplifier le processus de vente et vendre votre bague, pendentif ou vos boucles d\u2019oreilles Cosmos Van Cleef &amp; Arpels au meilleur prix, passez par Diamantaires Paris OG. Nous vous accueillons dans notre boutique du 43 Rue Beaubourg 75003 Paris, avec ou sans rendez-vous, et nous vous proposons une expertise gratuite et sans engagement de vos bijoux \u00e0 vendre. N\u2019h\u00e9sitez pas \u00e0 remplir le formulaire ci-dessous pour b\u00e9n\u00e9ficier d\u2019une expertise gratuite de votre bijou Cosmos\u00a0! Une fois la vente conclue aupr\u00e8s de nos experts, le paiement est imm\u00e9diat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-833a336 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"833a336\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" aria-label=\"Nouveau formulaire\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"10649\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"833a336\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Vendre collection Cosmos Van Cleef &amp; Arpels\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"10649\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_ffa63ad elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_ffa63ad\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPr\u00e9nom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_ffa63ad]\" id=\"form-field-field_ffa63ad\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pr\u00e9nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_e990a88 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_e990a88\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tT\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_e990a88]\" id=\"form-field-field_e990a88\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDescriptif du bijou Van Cleef & Arpels\u00e0 expertiser \t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Descriptif du bijou Van Cleef &amp; Arpels \u00e0 expertiser \"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_e06af6f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_e06af6f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPhotos de votre bijou (non obligatoire)\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_e06af6f][]\" id=\"form-field-field_e06af6f\" class=\"elementor-field elementor-size-sm  elementor-upload-field\" multiple=\"multiple\" data-maxsize=\"5\" data-maxsize-message=\"This file exceeds the maximum allowed size.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-shrink\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-signature\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander expertise gratuite<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3480f4d elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"3480f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"tel:0148878144\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t01 48 87 81 44\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tNotre service client\u00e8le se tient gratuitement \u00e0 votre disposition pour plus d'information sur notre m\u00e9tier de Diamantaire \u00e0 Paris.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ebe503e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebe503e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3a3e8c\" data-id=\"d3a3e8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3e92f8 elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"b3e92f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;2&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-10712 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/a-cheval\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"402\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-A-cheval-768x402.jpg\" class=\"attachment-medium_large size-medium_large wp-image-10714\" alt=\"Vendre bijou collection A cheval\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-A-cheval-768x402.jpg 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-A-cheval-300x157.jpg 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-A-cheval-1024x536.jpg 1024w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-A-cheval.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/a-cheval\/\">\n\t\t\t\tVendre collection A cheval Van Cleef &#038; Arpels\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La Maison Van Cleef &amp; Arpels est l\u2019une des maisons de Haute Joaillerie fran\u00e7aises les plus r\u00e9put\u00e9es en France comme \u00e0 l\u2019international. Encens\u00e9e pour son<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/a-cheval\/\" aria-label=\"Read more about Vendre collection A cheval Van Cleef &#038; Arpels\" tabindex=\"-1\">\n\t\t\tLire la suite \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-10649 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/cosmos\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"402\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-768x402.jpg\" class=\"attachment-medium_large size-medium_large wp-image-10653\" alt=\"Vendre bijou collection Cosmos\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-768x402.jpg 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-300x157.jpg 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos-1024x536.jpg 1024w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2022\/09\/Vendre-bijou-collection-Cosmos.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/cosmos\/\">\n\t\t\t\tVendre collection Cosmos Van Cleef &#038; Arpels\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Expertisez vos bijoux Van Cleef &amp; Arpels 01 48 87 81 44 Vendre La Maison Van Cleef &amp; Arpels, c\u2019est un m\u00e9lange d\u2019\u00e9l\u00e9gance et de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/cosmos\/\" aria-label=\"Read more about Vendre collection Cosmos Van Cleef &#038; Arpels\" tabindex=\"-1\">\n\t\t\tLire la suite \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be3ab1e elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-global elementor-global-6974 elementor-widget-icon-box\" data-id=\"be3ab1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDiamantaire Paris propose une alternative de rachat imm\u00e9diat de bijoux sans vendre aux ench\u00e8res.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPlus d'infos sans rendez vous au 43 rue Beaubourg 75003 Paris, ou par t\u00e9l\u00e9phone : +33 1 48 87 23 37 \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4ad0a9 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"b4ad0a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6279 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chanel\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel--300x300.png\" class=\"attachment-medium size-medium wp-image-6281\" alt=\"Vendre un bijou de la Maison Chanel\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel--300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel--150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel--768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel--400x400.png 400w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-de-la-Maison-Chanel-.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chanel\/\">\n\t\t\t\tVendre Bijoux Chanel\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Si la Maison Chanel est surtout connue dans le milieu de la mode, elle est \u00e0 l\u2019origine de plusieurs collections de Haute Joaillerie<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chanel\/\" aria-label=\"Read more about Vendre Bijoux Chanel\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6245 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-harry-winston\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4-300x300.png\" class=\"attachment-medium size-medium wp-image-6252\" alt=\"Vendre son bijou Harry Winston(4)\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4-300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4-150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4-768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4-400x400.png 400w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-4.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-harry-winston\/\">\n\t\t\t\tVendre Bijoux Harry Winston\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vendez vos bijoux Harry Winston 01 48 87 81 44 Vendre Harry Winston est l\u2019une des Maisons de joaillerie les plus glamour. Le<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-harry-winston\/\" aria-label=\"Read more about Vendre Bijoux Harry Winston\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6214 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chaumet\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-300x300.png\" class=\"attachment-medium size-medium wp-image-6216\" alt=\"Vendre son bijou Chaumet avec Diamantaires Paris\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet-400x400.png 400w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-son-bijou-Chaumet.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chaumet\/\">\n\t\t\t\tVendre Bijoux Chaumet\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Vendez vos bijoux Chaumet 01 48 87 81 44 Vendre La Maison Chaumet, l\u2019une des plus anciennes maisons de haute joaillerie de France<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-chaumet\/\" aria-label=\"Read more about Vendre Bijoux Chaumet\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6169 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-damiani\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani-300x300.png\" class=\"attachment-medium size-medium wp-image-6170\" alt=\"Vendre un bijou Damiani\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani-300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani-150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani-768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani-400x400.png 400w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/10\/Vendre-un-bijou-Damiani.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-damiani\/\">\n\t\t\t\tVendre Bijoux Damiani\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La Maison Damiani est l\u2019une des premi\u00e8res repr\u00e9sentantes de la Haute Joaillerie italienne. Fond\u00e9e il y a pr\u00e8s d\u2019un si\u00e8cle, elle n\u2019a cess\u00e9<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/vendre-bijoux-damiani\/\" aria-label=\"Read more about Vendre Bijoux Damiani\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5520 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-300x300.png\" class=\"attachment-medium size-medium wp-image-5522\" alt=\"Van Cleef &amp; Arpels\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-1024x1024.png 1024w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-1536x1536.png 1536w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels.png 2048w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/05\/Van-Cleef-Arpels-400x400.png 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/\">\n\t\t\t\tVendre un bijou Van Cleef &#038; Arpels\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La Maison Van Cleef &amp; Arpels est r\u00e9put\u00e9e pour la qualit\u00e9 de ses savoir-faire, dont la technique brevet\u00e9e du Serti Myst\u00e9rieux, et le<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-haute-joaillerie\/van-cleef-arpels\/\" aria-label=\"Read more about Vendre un bijou Van Cleef &#038; Arpels\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4212 page type-page status-publish has-post-thumbnail hentry\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-un-bien\/bijoux-anciens\/les-bijoux-cartier\/\" tabindex=\"-1\"><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier-300x300.png\" class=\"attachment-medium size-medium wp-image-5700\" alt=\"Vendre un bijou Cartier avec Diamantaires Paris\" srcset=\"https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier-300x300.png 300w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier-150x150.png 150w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier-768x768.png 768w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier-400x400.png 400w, https:\/\/diamantaire-paris.com\/wp-content\/uploads\/2020\/06\/Vendre-un-bijou-Cartier.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\"><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" alt=\"obagem\" src=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=128&#038;d=mm&#038;r=g\" srcset=\"https:\/\/secure.gravatar.com\/avatar\/5db45a8a0044a1fa01d4eccb3bca84b019ebd1bcc0c2d33fbdf4dc92c639059b?s=256&#038;d=mm&#038;r=g 2x\" class=\"avatar avatar-128 photo\" height=\"128\" width=\"128\" title=\"\">\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/diamantaire-paris.com\/en\/vendre-un-bien\/bijoux-anciens\/les-bijoux-cartier\/\">\n\t\t\t\tVendre bijoux Cartier\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Cr\u00e9atrice de produits et accessoires de luxe, la Maison Cartier s\u2019impose dans l\u2019univers de la joaillerie de luxe fran\u00e7aise depuis bien des g\u00e9n\u00e9rations.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/diamantaire-paris.com\/en\/vendre-un-bien\/bijoux-anciens\/les-bijoux-cartier\/\" aria-label=\"Read more about Vendre bijoux Cartier\" tabindex=\"-1\">\n\t\t\tLire plus sur ce grands joailliers\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce56870 elementor-widget elementor-widget-accordion\" data-id=\"ce56870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2161\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2161\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelle est la sp\u00e9cificit\u00e9 de la collection Cosmos de Van Cleef & Arpels ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2161\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2161\"><p>La collection Cosmos de Van Cleef &amp; Arpels, cr\u00e9\u00e9e en 2014, s&rsquo;inspire d&rsquo;une fleur signature de la Maison, con\u00e7ue dans les ann\u00e9es 50. Cette fleur est compos\u00e9e de quatre p\u00e9tales en forme de c\u0153ur, inspir\u00e9s du tr\u00e8fle \u00e0 quatre feuilles. La collection utilise principalement le nacre et l&rsquo;onyx, avec des bijoux en or rose, nacre et diamants, ou en or blanc, onyx et diamants.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2162\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2162\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment vendre un bijou de la collection Cosmos chez Diamantaire Paris OG ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2162\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2162\"><p>Pour vendre un bijou de la collection Cosmos, vous pouvez vous rendre \u00e0 la boutique Diamantaire Paris OG au 43 Rue Beaubourg, 75003 Paris, avec ou sans rendez-vous, ou demander une expertise gratuite en remplissant un formulaire en ligne sur leur site. Ils offrent une \u00e9valuation pr\u00e9cise et juste de chaque bijou.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2163\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2163\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelle est la politique de Diamantaire Paris OG pour les offres de rachat de bijoux Van Cleef & Arpels ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2163\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2163\"><p>Diamantaire Paris OG propose les meilleures offres de rachat du march\u00e9 pour les bijoux Van Cleef &amp; Arpels. Si vous avez une meilleure offre ailleurs, ils s&rsquo;engagent \u00e0 faire une offre sup\u00e9rieure, assurant la meilleure valeur pour votre bijou.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2164\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2164\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quels types de bijoux Van Cleef & Arpels sont rachet\u00e9s par Diamantaire Paris OG ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2164\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2164\"><p>Diamantaire Paris OG rach\u00e8te une large gamme de bijoux Van Cleef &amp; Arpels, y compris des pi\u00e8ces de collections r\u00e9centes ou plus anciennes, en or jaune ou orn\u00e9es de diamants, \u00e9meraudes et saphirs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2165\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2165\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment contacter Diamantaire Paris OG et quels sont leurs horaires d'ouverture ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2165\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2165\"><div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-yrgnd-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-yrgnd-1n7m0yu\"><div class=\"flex flex-col text-sm pb-9\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-89\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\"><div class=\"relative flex w-full flex-col agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"91b767f9-b166-4e62-abb2-b0e4083414f6\"><div class=\"markdown prose w-full break-words dark:prose-invert dark\"><p>Diamantaire Paris OG est ouvert du lundi au vendredi de 10h \u00e0 13h et de 14h \u00e0 19h. Vous pouvez les contacter par t\u00e9l\u00e9phone au 01 48 87 23 37 ou par email \u00e0 <a target=\"_new\">achat@diamantaire-paris.com<\/a>. Leur boutique est situ\u00e9e \u00e0 proximit\u00e9 du m\u00e9tro R\u00e9aumur &#8211; S\u00e9bastopol.<\/p><\/div><\/div><\/div><div class=\"mt-1 flex justify-start gap-3 empty:hidden\"><div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 -ml-1 h-7 visible\"><button class=\"flex items-center gap-1.5 rounded-md p-1 text-xs text-token-text-tertiary hover:text-token-text-primary md:invisible md:group-hover:visible md:group-[.final-completion]:visible\"><\/button><div class=\"flex items-center gap-1.5 text-xs\">\u00a0<\/div><div class=\"flex\">\u00a0<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\"><form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\"><div class=\"relative flex h-full flex-1 flex-col\"><div class=\"flex w-full items-center\">\u00a0<\/div><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Quelle est la sp\\u00e9cificit\\u00e9 de la collection Cosmos de Van Cleef & Arpels ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La collection Cosmos de Van Cleef &amp; Arpels, cr\\u00e9\\u00e9e en 2014, s&rsquo;inspire d&rsquo;une fleur signature de la Maison, con\\u00e7ue dans les ann\\u00e9es 50. Cette fleur est compos\\u00e9e de quatre p\\u00e9tales en forme de c\\u0153ur, inspir\\u00e9s du tr\\u00e8fle \\u00e0 quatre feuilles. La collection utilise principalement le nacre et l&rsquo;onyx, avec des bijoux en or rose, nacre et diamants, ou en or blanc, onyx et diamants.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Comment vendre un bijou de la collection Cosmos chez Diamantaire Paris OG ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Pour vendre un bijou de la collection Cosmos, vous pouvez vous rendre \\u00e0 la boutique Diamantaire Paris OG au 43 Rue Beaubourg, 75003 Paris, avec ou sans rendez-vous, ou demander une expertise gratuite en remplissant un formulaire en ligne sur leur site. Ils offrent une \\u00e9valuation pr\\u00e9cise et juste de chaque bijou.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quelle est la politique de Diamantaire Paris OG pour les offres de rachat de bijoux Van Cleef & Arpels ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Diamantaire Paris OG propose les meilleures offres de rachat du march\\u00e9 pour les bijoux Van Cleef &amp; Arpels. Si vous avez une meilleure offre ailleurs, ils s&rsquo;engagent \\u00e0 faire une offre sup\\u00e9rieure, assurant la meilleure valeur pour votre bijou.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quels types de bijoux Van Cleef & Arpels sont rachet\\u00e9s par Diamantaire Paris OG ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Diamantaire Paris OG rach\\u00e8te une large gamme de bijoux Van Cleef &amp; Arpels, y compris des pi\\u00e8ces de collections r\\u00e9centes ou plus anciennes, en or jaune ou orn\\u00e9es de diamants, \\u00e9meraudes et saphirs.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Comment contacter Diamantaire Paris OG et quels sont leurs horaires d'ouverture ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<div class=\\\"flex-1 overflow-hidden\\\"><div class=\\\"react-scroll-to-bottom--css-yrgnd-79elbk h-full\\\"><div class=\\\"react-scroll-to-bottom--css-yrgnd-1n7m0yu\\\"><div class=\\\"flex flex-col text-sm pb-9\\\"><div class=\\\"w-full text-token-text-primary\\\" data-testid=\\\"conversation-turn-89\\\"><div class=\\\"px-4 py-2 justify-center text-base md:gap-6 m-auto\\\"><div class=\\\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\\\"><div class=\\\"relative flex w-full flex-col agent-turn\\\"><div class=\\\"flex-col gap-1 md:gap-3\\\"><div class=\\\"flex flex-grow flex-col max-w-full\\\"><div class=\\\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\\\" data-message-author-role=\\\"assistant\\\" data-message-id=\\\"91b767f9-b166-4e62-abb2-b0e4083414f6\\\"><div class=\\\"markdown prose w-full break-words dark:prose-invert dark\\\"><p>Diamantaire Paris OG est ouvert du lundi au vendredi de 10h \\u00e0 13h et de 14h \\u00e0 19h. Vous pouvez les contacter par t\\u00e9l\\u00e9phone au 01 48 87 23 37 ou par email \\u00e0 <a target=\\\"_new\\\">achat@diamantaire-paris.com<\\\/a>. Leur boutique est situ\\u00e9e \\u00e0 proximit\\u00e9 du m\\u00e9tro R\\u00e9aumur &#8211; S\\u00e9bastopol.<\\\/p><\\\/div><\\\/div><\\\/div><div class=\\\"mt-1 flex justify-start gap-3 empty:hidden\\\"><div class=\\\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 -ml-1 h-7 visible\\\"><button class=\\\"flex items-center gap-1.5 rounded-md p-1 text-xs text-token-text-tertiary hover:text-token-text-primary md:invisible md:group-hover:visible md:group-[.final-completion]:visible\\\"><\\\/button><div class=\\\"flex items-center gap-1.5 text-xs\\\">\\u00a0<\\\/div><div class=\\\"flex\\\">\\u00a0<\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><\\\/div><div class=\\\"w-full pt-2 md:pt-0 dark:border-white\\\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\\\"><form class=\\\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\\\"><div class=\\\"relative flex h-full flex-1 flex-col\\\"><div class=\\\"flex w-full items-center\\\">\\u00a0<\\\/div><\\\/div><\\\/form><\\\/div>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b60e586 elementor-widget elementor-widget-text-editor\" data-id=\"b60e586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-qnuqh-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-qnuqh-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-115\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"69d9d6e0-0840-4d24-994f-3cb5cc3bfde8\"><div class=\"markdown prose w-full break-words dark:prose-invert dark\"><p>Diamantaire Paris, votre destination de choix pour la haute joaillerie, est fier de pr\u00e9senter la collection Van Cleef &amp; Arpels Cosmos, une c\u00e9l\u00e9bration de l&rsquo;\u00e9l\u00e9gance et de la sophistication. Notre maison, nich\u00e9e au c\u0153ur de la prestigieuse place Vend\u00f4me, est reconnue pour son <strong><a href=\"https:\/\/diamantaire-paris.com\/heritage\/rachat-diamants\/vendome-expertise\/\" target=\"_new\">expertise de bijou issue de la place Vendome<\/a><\/strong>, offrant une exp\u00e9rience in\u00e9gal\u00e9e \u00e0 ceux qui cherchent \u00e0 vendre ou acqu\u00e9rir des pi\u00e8ces de haute joaillerie.<\/p><p>Nous comprenons que chaque bijou a une histoire \u00e0 raconter. C&rsquo;est pourquoi nous offrons une <strong><a href=\"https:\/\/diamantaire-paris.com\/vendre-un-bien\/estimation-bijoux\/\" target=\"_new\">estimation gratuite de bijou<\/a><\/strong>, assurant que chaque pi\u00e8ce est \u00e9valu\u00e9e avec le soin et l&rsquo;attention qu&rsquo;elle m\u00e9rite. Que vous cherchiez \u00e0 <strong><a href=\"https:\/\/diamantaire-paris.com\/vendre-un-bien\/bijoux-anciens\/bagues-anciennes\/\" target=\"_new\">vendre une bague ancienne<\/a><\/strong> ou \u00e0 d\u00e9couvrir la valeur d&rsquo;un <strong><a href=\"https:\/\/diamantaire-paris.com\/vendre-un-bien\/diamant-retro\/\" target=\"_new\">diamant retro<\/a><\/strong>, notre \u00e9quipe d&rsquo;experts est l\u00e0 pour vous accompagner \u00e0 chaque \u00e9tape.<\/p><p>Notre r\u00e9putation en tant que leader dans le domaine des bijoux de luxe est renforc\u00e9e par notre engagement \u00e0 offrir un service personnalis\u00e9 et professionnel. Nous sommes fiers de notre collection, notamment des pi\u00e8ces de Van Cleef &amp; Arpels, et nous nous engageons \u00e0 maintenir les normes les plus \u00e9lev\u00e9es dans toutes nos transactions.<\/p><p>Pour ceux qui cherchent \u00e0 \u00e9valuer ou vendre des bijoux de cr\u00e9ateurs, notre <strong><a href=\"https:\/\/diamantaire-paris.com\/vendre-un-bien\/alternative-a-sothebys\/\" target=\"_new\">alternative \u00e0 Sothebys pour vendre un bijou<\/a><\/strong> garantit une \u00e9valuation pr\u00e9cise et juste. Nous comprenons la valeur sentimentale et financi\u00e8re de chaque pi\u00e8ce et nous nous effor\u00e7ons de fournir une exp\u00e9rience transparente et satisfaisante.<\/p><p>Si vous poss\u00e9dez des bijoux de haute joaillerie et que vous envisagez de vendre, ou si vous souhaitez simplement en savoir plus sur notre collection et nos services, <strong><a href=\"https:\/\/diamantaire-paris.com\/contact\/\" target=\"_new\">contactez-nous<\/a><\/strong>. Chez Diamantaire Paris, chaque bijou est une histoire, et nous sommes l\u00e0 pour vous aider \u00e0 \u00e9crire le prochain chapitre.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expertisez vos bijoux Van Cleef &amp; Arpels 01 48 87 81 44 Vendre La Maison Van Cleef &amp; Arpels, c\u2019est un m\u00e9lange d\u2019\u00e9l\u00e9gance et de savoir-faire. Les bijoux Van Cleef &amp; Arpels sont uniques gr\u00e2ce \u00e0 des techniques brevet\u00e9es, et \u00e0 des motifs inspir\u00e9s de la Nature stylis\u00e9s par les plus grands designers. Van Cleef [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10653,"parent":5520,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-10649","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/pages\/10649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/comments?post=10649"}],"version-history":[{"count":21,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/pages\/10649\/revisions"}],"predecessor-version":[{"id":20112,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/pages\/10649\/revisions\/20112"}],"up":[{"embeddable":true,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/pages\/5520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/media\/10653"}],"wp:attachment":[{"href":"https:\/\/diamantaire-paris.com\/en\/wp-json\/wp\/v2\/media?parent=10649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}